{"id":48270,"date":"2024-01-04T17:46:08","date_gmt":"2024-01-04T15:46:08","guid":{"rendered":"https:\/\/novare.se\/?page_id=48270"},"modified":"2025-01-15T14:35:49","modified_gmt":"2025-01-15T12:35:49","slug":"our-team","status":"publish","type":"page","link":"https:\/\/novare.se\/en\/our-team\/","title":{"rendered":"Our Team"},"content":{"rendered":"<section id=\"hero-3-block_530723ecc5f0132da737f40b3ce505c9\" class=\"block hero-3  m-b no-img \">\n    <div class=\"hero-3--top-section bg-primary\">\n                    <div class=\"bg-backdrop\">\n                <div class=\"bg-backdrop--inner\"><\/div>\n            <\/div>\n                <div class=\"container\">\n            <div class=\"row\">\n                <div class=\"row__col\">\n                    <div class=\"text-img-wrapper\">\n                        <div class=\"text-col\" >\n                                                                \n                                <div class=\"title-wrapper\" data-aos-anchor='#hero-3-block_530723ecc5f0132da737f40b3ce505c9'data-aos='fade-in'data-aos-easing='ease-in-out-sine'data-aos-duration='500'data-aos-delay='300'data-aos-once='true'data-aos-offset='250'>\n                                    <h1 class=\"h1 text-left\">Our Team <\/h1>                                <\/div>\n                                                            \n                            \n                            \n                                                    <\/div>\n\n                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n            <div class=\"hero-3--bottom-section \" data-aos-anchor='#hero-3-block_530723ecc5f0132da737f40b3ce505c9'data-aos='fade-in'data-aos-easing='ease-in-out-sine'data-aos-duration='500'data-aos-delay='550'data-aos-once='true'data-aos-offset='250' >\n        <div class=\"breadcrumbs dark-text\">\n\t<div class=\"container\">\n        <div class=\"row\">\n            <div class=\"row__col\">\n                <div class=\"breadcrumbs--inner\">\n                    <ul>\n                        \t\t\t                                                                    <li>\n                                <a href=\"https:\/\/novare.se\/en\/\" class=\"alt\">\n                                                                            Novare                                                                    <\/a>\n                            <\/li>\n\t\t\t                                    <li><span class=\"alt\">Our Team<\/span><\/li>\n                    <\/ul>\n                <\/div>\n            <\/div>\n        <\/div>\n\t<\/div>\n<\/div>\n        <\/div>\n    \n    <\/section>\n\n\n<section id=\"987\" class=\"block employee-search-block  m-b bg-default\">\n    <div class=\"container\">\n        <form class=\"listing-block--filters\" data-url=\"https:\/\/novare.se\/en\/wp-json\/wp\/v2\/pages\/48270\/\/\">\n            <div class=\"row\">\n                <div class=\"row__col\">\n                    <div class=\"listing-block--filters-inner search\">\n                        \n                        <div class=\"filters\">\n                                                            <div class=\"select-wrapper filter\">\n                                    <label for=\"company\" class=\"text-medium\">Novare company<\/label>\n                                    <div class=\"field\">\n                                        <select class=\"js-select-filter\" name=\"company\" id=\"company\">\n                                            <option value=\"\" selected>All<\/option>\n                                                                                                                                                                                                                                                                                        <option value=\"executive-search\" >Novare Executive Search<\/option>\n                                                                                                                                                                                            <option value=\"intro\" >Novare Intro<\/option>\n                                                                                                                                                                                            <option value=\"interim-and-recruitment\" >Novare Interim &#038; Recruitment<\/option>\n                                                                                                                                                                                            <option value=\"public\" >Novare Public<\/option>\n                                                                                                                                                                                            <option value=\"bemanning\" >Novare Bemanning<\/option>\n                                                                                                                                                                                            <option value=\"leadership\" >Novare Leadership<\/option>\n                                                                                                                                                                                            <option value=\"tech\" >Novare Tech<\/option>\n                                                                                    <\/select>\n                                    <\/div>\n                                <\/div>\n                                                        \n                            <div class=\"select-wrapper filter \">\n                                <label for=\"team\" class=\"text-medium\">Team<\/label>\n                                <div class=\"field\">\n                                    <select class=\"js-select-filter\" name=\"team\" id=\"team\">\n                                        <option value=\"\" selected>All<\/option>\n                                                                                                                                    <option value=\"novare-executive-search\"  >Novare Executive Search<\/option>\n                                                                                            <option value=\"novare-human-capital\"  >Novare Human Capital<\/option>\n                                                                                            <option value=\"novare-pay\"  >Novare Pay<\/option>\n                                                                                            <option value=\"novare-leadership-academy\"  >Novare Leadership Academy<\/option>\n                                                                                                                        <\/select>\n                                <\/div>\n                            <\/div> \n                        <\/div>\n\n                        <div class=\"filters--end\">\n                            <div class=\"input-wrapper\" >\n                                <div class=\"field\">\n                                                                        <input class=\"js-search-field\" type=\"search\" name=\"search\" placeholder=\"Search for name or job title\" value=\"\" \/>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n\n                    <\/div>\n                <\/div>\n            <\/div>\n            <input type=\"hidden\" name=\"posts_per_page\" value=\"20\" data-large=\"20\" data-small=\"10\">\n            <input type=\"hidden\" name=\"page_no\" value=\"1\">\n            <input type=\"hidden\" name=\"selected_team\" value=\"\">\n            <input type=\"hidden\" name=\"selected_company\" value=\"\">\n        <\/form>\n\n        <div class=\"row listing-block--results\">\n                                                \n<div class=\"row__col row__col--lg-3 listing-block--item cols-4\" >\n    <div class=\"listing-block--item-inner\">\n                <a class=\"m-0\" href=\"https:\/\/novare.se\/en\/employees\/alice-wallenberg\/\">\n            <div class=\"image m-0\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/novare.se\/wp-content\/uploads\/2026\/05\/alice_wallenberg_webb-768x768.jpg\" class=\"media-item\" alt=\"\" srcset=\"https:\/\/novare.se\/wp-content\/uploads\/2026\/05\/alice_wallenberg_webb-768x768.jpg 768w, https:\/\/novare.se\/wp-content\/uploads\/2026\/05\/alice_wallenberg_webb-360x360.jpg 360w, https:\/\/novare.se\/wp-content\/uploads\/2026\/05\/alice_wallenberg_webb-150x150.jpg 150w, https:\/\/novare.se\/wp-content\/uploads\/2026\/05\/alice_wallenberg_webb.jpg 1024w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>                <div class=\"overlay\"><\/div>\n                <div class=\"badge text-regular\" style=\"background-color: #f5f2ef; color: #000000;\">Novare<\/div>            <\/div>\n        <\/a>\n        <div class=\"content\">\n            <div class=\"header\">\n                <div class=\"name\">\n                    <a class=\"m-0\" href=\"https:\/\/novare.se\/en\/employees\/alice-wallenberg\/\">\n                        <div class=\"title text-medium\"><p>Alice Wallenberg<\/p><\/div>\n                    <\/a>\n                    <div class=\"pre_title\"><p>Project Coordinator in Finance, Commercial, and Communications<\/p><\/div>\n                <\/div>\n                                    <div class=\"contact-info\">\n                        <a class=\"m-0\" href=\"mailto:alice.wallenberg@novare.se\"><span class=\"text-medium\">alice.wallenberg@novare.se<\/span><\/a>  \n                          \n                    <\/div>\n                  \n            <\/div>\n                \n            <a class=\"m-0 read-more\" href=\"https:\/\/novare.se\/en\/employees\/alice-wallenberg\/\">\n                <span class=\"text-medium\">Read more about Alice<\/span><i class=\"arrow fa fa-arrow-right\" aria-hidden=\"true\"><\/i>\n            <\/a>\n        <\/div>\n    <\/div>\n    \n<\/div>\n                                    \n<div class=\"row__col row__col--lg-3 listing-block--item cols-4\" >\n    <div class=\"listing-block--item-inner\">\n                <a class=\"m-0\" href=\"https:\/\/novare.se\/interim-and-recruitment\/en\/employees\/amanda-hallgren\/\">\n            <div class=\"image m-0\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/novare.se\/wp-content\/uploads\/sites\/5\/2024\/05\/Amanda-768x768.jpg\" class=\"media-item\" alt=\"Leende kvinna med brun tr\u00f6ja.\" srcset=\"https:\/\/novare.se\/wp-content\/uploads\/sites\/5\/2024\/05\/Amanda-768x768.jpg 768w, https:\/\/novare.se\/wp-content\/uploads\/sites\/5\/2024\/05\/Amanda-360x360.jpg 360w, https:\/\/novare.se\/wp-content\/uploads\/sites\/5\/2024\/05\/Amanda-1024x1024.jpg 1024w, https:\/\/novare.se\/wp-content\/uploads\/sites\/5\/2024\/05\/Amanda-150x150.jpg 150w, https:\/\/novare.se\/wp-content\/uploads\/sites\/5\/2024\/05\/Amanda-1536x1536.jpg 1536w, https:\/\/novare.se\/wp-content\/uploads\/sites\/5\/2024\/05\/Amanda.jpg 2000w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>                <div class=\"overlay\"><\/div>\n                <div class=\"badge text-regular\" style=\"background-color: #f5f2ef; color: #000000;\">Novare Interim &#038; Recruitment<\/div>            <\/div>\n        <\/a>\n        <div class=\"content\">\n            <div class=\"header\">\n                <div class=\"name\">\n                    <a class=\"m-0\" href=\"https:\/\/novare.se\/interim-and-recruitment\/en\/employees\/amanda-hallgren\/\">\n                        <div class=\"title text-medium\"><p>Amanda Hallgren<\/p><\/div>\n                    <\/a>\n                    <div class=\"pre_title\"><p>Account Executive Interim<\/p><\/div>\n                <\/div>\n                                    <div class=\"contact-info\">\n                        <a class=\"m-0\" href=\"mailto:amanda.hallgren@novare.se\"><span class=\"text-medium\">amanda.hallgren@novare.se<\/span><\/a>  \n                        <a class=\"m-0\" href=\"tel:+46 760 80 68 27\"><span class=\"text-medium\">+46 760 80 68 27<\/span><\/a>  \n                    <\/div>\n                  \n            <\/div>\n                \n            <a class=\"m-0 read-more\" href=\"https:\/\/novare.se\/interim-and-recruitment\/en\/employees\/amanda-hallgren\/\">\n                <span class=\"text-medium\">Read more about Amanda<\/span><i class=\"arrow fa fa-arrow-right\" aria-hidden=\"true\"><\/i>\n            <\/a>\n        <\/div>\n    <\/div>\n    \n<\/div>\n                                    \n<div class=\"row__col row__col--lg-3 listing-block--item cols-4\" >\n    <div class=\"listing-block--item-inner\">\n                <a class=\"m-0\" href=\"https:\/\/novare.se\/executive-search\/en\/employees\/ambjorn-ingvaldson\/\">\n            <div class=\"image m-0\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"670\" height=\"480\" src=\"https:\/\/novare.se\/wp-content\/uploads\/sites\/2\/2024\/04\/Ambjorn_Ingvaldson_Tiny.jpg\" class=\"media-item\" alt=\"\" srcset=\"https:\/\/novare.se\/wp-content\/uploads\/sites\/2\/2024\/04\/Ambjorn_Ingvaldson_Tiny.jpg 670w, https:\/\/novare.se\/wp-content\/uploads\/sites\/2\/2024\/04\/Ambjorn_Ingvaldson_Tiny-180x129.jpg 180w, https:\/\/novare.se\/wp-content\/uploads\/sites\/2\/2024\/04\/Ambjorn_Ingvaldson_Tiny-200x143.jpg 200w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/>                <div class=\"overlay\"><\/div>\n                <div class=\"badge text-regular\" style=\"background-color: #f5f2ef; color: #000000;\">Novare Executive Search<\/div>            <\/div>\n        <\/a>\n        <div class=\"content\">\n            <div class=\"header\">\n                <div class=\"name\">\n                    <a class=\"m-0\" href=\"https:\/\/novare.se\/executive-search\/en\/employees\/ambjorn-ingvaldson\/\">\n                        <div class=\"title text-medium\"><p>Ambj\u00f6rn Ingvaldson<\/p><\/div>\n                    <\/a>\n                    <div class=\"pre_title\"><p>Junior Consultant<\/p><\/div>\n                <\/div>\n                                    <div class=\"contact-info\">\n                        <a class=\"m-0\" href=\"mailto:ambjorn.ingvaldson@novare.se\"><span class=\"text-medium\">ambjorn.ingvaldson@novare.se<\/span><\/a>  \n                        <a class=\"m-0\" href=\"tel:+46 761 62 36 89\"><span class=\"text-medium\">+46 761 62 36 89<\/span><\/a>  \n                    <\/div>\n                  \n            <\/div>\n                \n            <a class=\"m-0 read-more\" href=\"https:\/\/novare.se\/executive-search\/en\/employees\/ambjorn-ingvaldson\/\">\n                <span class=\"text-medium\">Read more about Ambj\u00f6rn<\/span><i class=\"arrow fa fa-arrow-right\" aria-hidden=\"true\"><\/i>\n            <\/a>\n        <\/div>\n    <\/div>\n    \n<\/div>\n                                    \n<div class=\"row__col row__col--lg-3 listing-block--item cols-4\" >\n    <div class=\"listing-block--item-inner\">\n                <a class=\"m-0\" href=\"https:\/\/novare.se\/executive-search\/en\/employees\/anders-cedermark\/\">\n            <div class=\"image m-0\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"670\" height=\"480\" src=\"https:\/\/novare.se\/wp-content\/uploads\/sites\/2\/2024\/04\/Anders_Cedermark_Tiny.jpg\" class=\"media-item\" alt=\"\" srcset=\"https:\/\/novare.se\/wp-content\/uploads\/sites\/2\/2024\/04\/Anders_Cedermark_Tiny.jpg 670w, https:\/\/novare.se\/wp-content\/uploads\/sites\/2\/2024\/04\/Anders_Cedermark_Tiny-180x129.jpg 180w, https:\/\/novare.se\/wp-content\/uploads\/sites\/2\/2024\/04\/Anders_Cedermark_Tiny-200x143.jpg 200w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/>                <div class=\"overlay\"><\/div>\n                <div class=\"badge text-regular\" style=\"background-color: #f5f2ef; color: #000000;\">Novare Executive Search<\/div>            <\/div>\n        <\/a>\n        <div class=\"content\">\n            <div class=\"header\">\n                <div class=\"name\">\n                    <a class=\"m-0\" href=\"https:\/\/novare.se\/executive-search\/en\/employees\/anders-cedermark\/\">\n                        <div class=\"title text-medium\"><p>Anders Cedermark<\/p><\/div>\n                    <\/a>\n                    <div class=\"pre_title\"><p>Senior Partner &#038; Senior Consultant<\/p><\/div>\n                <\/div>\n                                    <div class=\"contact-info\">\n                        <a class=\"m-0\" href=\"mailto:anders.cedermark@novare.se\"><span class=\"text-medium\">anders.cedermark@novare.se<\/span><\/a>  \n                        <a class=\"m-0\" href=\"tel:+46 707 92 20 75\"><span class=\"text-medium\">+46 707 92 20 75<\/span><\/a>  \n                    <\/div>\n                  \n            <\/div>\n                \n            <a class=\"m-0 read-more\" href=\"https:\/\/novare.se\/executive-search\/en\/employees\/anders-cedermark\/\">\n                <span class=\"text-medium\">Read more about Anders<\/span><i class=\"arrow fa fa-arrow-right\" aria-hidden=\"true\"><\/i>\n            <\/a>\n        <\/div>\n    <\/div>\n    \n<\/div>\n                                    \n<div class=\"row__col row__col--lg-3 listing-block--item cols-4\" >\n    <div class=\"listing-block--item-inner\">\n                <a class=\"m-0\" href=\"https:\/\/novare.se\/executive-search\/en\/employees\/andreas-lokken\/\">\n            <div class=\"image m-0\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"670\" height=\"480\" src=\"https:\/\/novare.se\/wp-content\/uploads\/sites\/2\/2024\/05\/Andreas_Looken_Tiny.jpg\" class=\"media-item\" alt=\"\" srcset=\"https:\/\/novare.se\/wp-content\/uploads\/sites\/2\/2024\/05\/Andreas_Looken_Tiny.jpg 670w, https:\/\/novare.se\/wp-content\/uploads\/sites\/2\/2024\/05\/Andreas_Looken_Tiny-180x129.jpg 180w, https:\/\/novare.se\/wp-content\/uploads\/sites\/2\/2024\/05\/Andreas_Looken_Tiny-200x143.jpg 200w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/>                <div class=\"overlay\"><\/div>\n                <div class=\"badge text-regular\" style=\"background-color: #f5f2ef; color: #000000;\">Novare Executive Search<\/div>            <\/div>\n        <\/a>\n        <div class=\"content\">\n            <div class=\"header\">\n                <div class=\"name\">\n                    <a class=\"m-0\" href=\"https:\/\/novare.se\/executive-search\/en\/employees\/andreas-lokken\/\">\n                        <div class=\"title text-medium\"><p>Andreas L\u00f6kken<\/p><\/div>\n                    <\/a>\n                    <div class=\"pre_title\"><p>Head of Executive Assessment &#038; Senior Consultant<\/p><\/div>\n                <\/div>\n                                    <div class=\"contact-info\">\n                        <a class=\"m-0\" href=\"mailto:andreas.lokken@novare.se\"><span class=\"text-medium\">andreas.lokken@novare.se<\/span><\/a>  \n                        <a class=\"m-0\" href=\"tel:+46 735 02 50 62\"><span class=\"text-medium\">+46 735 02 50 62<\/span><\/a>  \n                    <\/div>\n                  \n            <\/div>\n                \n            <a class=\"m-0 read-more\" href=\"https:\/\/novare.se\/executive-search\/en\/employees\/andreas-lokken\/\">\n                <span class=\"text-medium\">Read more about Andreas<\/span><i class=\"arrow fa fa-arrow-right\" aria-hidden=\"true\"><\/i>\n            <\/a>\n        <\/div>\n    <\/div>\n    \n<\/div>\n                                    \n<div class=\"row__col row__col--lg-3 listing-block--item cols-4\" >\n    <div class=\"listing-block--item-inner\">\n                <a class=\"m-0\" href=\"https:\/\/novare.se\/executive-search\/en\/employees\/anna-eriksson\/\">\n            <div class=\"image m-0\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"670\" height=\"480\" src=\"https:\/\/novare.se\/wp-content\/uploads\/sites\/2\/2024\/05\/anna_eriksson-Tiny.jpg\" class=\"media-item\" alt=\"\" srcset=\"https:\/\/novare.se\/wp-content\/uploads\/sites\/2\/2024\/05\/anna_eriksson-Tiny.jpg 670w, https:\/\/novare.se\/wp-content\/uploads\/sites\/2\/2024\/05\/anna_eriksson-Tiny-180x129.jpg 180w, https:\/\/novare.se\/wp-content\/uploads\/sites\/2\/2024\/05\/anna_eriksson-Tiny-200x143.jpg 200w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/>                <div class=\"overlay\"><\/div>\n                <div class=\"badge text-regular\" style=\"background-color: #f5f2ef; color: #000000;\">Novare Executive Search<\/div>            <\/div>\n        <\/a>\n        <div class=\"content\">\n            <div class=\"header\">\n                <div class=\"name\">\n                    <a class=\"m-0\" href=\"https:\/\/novare.se\/executive-search\/en\/employees\/anna-eriksson\/\">\n                        <div class=\"title text-medium\"><p>Anna Eriksson<\/p><\/div>\n                    <\/a>\n                    <div class=\"pre_title\"><p>Partner &#038; Senior Researcher<\/p><\/div>\n                <\/div>\n                                    <div class=\"contact-info\">\n                        <a class=\"m-0\" href=\"mailto:anna.eriksson@novare.se\"><span class=\"text-medium\">anna.eriksson@novare.se<\/span><\/a>  \n                        <a class=\"m-0\" href=\"tel:+46 706 09 57 34\"><span class=\"text-medium\">+46 706 09 57 34<\/span><\/a>  \n                    <\/div>\n                  \n            <\/div>\n                \n            <a class=\"m-0 read-more\" href=\"https:\/\/novare.se\/executive-search\/en\/employees\/anna-eriksson\/\">\n                <span class=\"text-medium\">Read more about Anna<\/span><i class=\"arrow fa fa-arrow-right\" aria-hidden=\"true\"><\/i>\n            <\/a>\n        <\/div>\n    <\/div>\n    \n<\/div>\n                                    \n<div class=\"row__col row__col--lg-3 listing-block--item cols-4\" >\n    <div class=\"listing-block--item-inner\">\n                <a class=\"m-0\" href=\"https:\/\/novare.se\/public\/en\/employees\/anna-jansson\/\">\n            <div class=\"image m-0\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"670\" height=\"480\" src=\"https:\/\/novare.se\/wp-content\/uploads\/sites\/6\/2024\/04\/Anna_Jansson_Tiny.jpg\" class=\"media-item\" alt=\"\" srcset=\"https:\/\/novare.se\/wp-content\/uploads\/sites\/6\/2024\/04\/Anna_Jansson_Tiny.jpg 670w, https:\/\/novare.se\/wp-content\/uploads\/sites\/6\/2024\/04\/Anna_Jansson_Tiny-180x129.jpg 180w, https:\/\/novare.se\/wp-content\/uploads\/sites\/6\/2024\/04\/Anna_Jansson_Tiny-200x143.jpg 200w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/>                <div class=\"overlay\"><\/div>\n                <div class=\"badge text-regular\" style=\"background-color: #f5f2ef; color: #000000;\">Novare Public<\/div>            <\/div>\n        <\/a>\n        <div class=\"content\">\n            <div class=\"header\">\n                <div class=\"name\">\n                    <a class=\"m-0\" href=\"https:\/\/novare.se\/public\/en\/employees\/anna-jansson\/\">\n                        <div class=\"title text-medium\"><p>Anna Jansson<\/p><\/div>\n                    <\/a>\n                    <div class=\"pre_title\"><p>Researcher<\/p><\/div>\n                <\/div>\n                                    <div class=\"contact-info\">\n                        <a class=\"m-0\" href=\"mailto:anna.jansson@novare.se\"><span class=\"text-medium\">anna.jansson@novare.se<\/span><\/a>  \n                        <a class=\"m-0\" href=\"tel:+46 735 28 64 37\"><span class=\"text-medium\">+46 735 28 64 37<\/span><\/a>  \n                    <\/div>\n                  \n            <\/div>\n                \n            <a class=\"m-0 read-more\" href=\"https:\/\/novare.se\/public\/en\/employees\/anna-jansson\/\">\n                <span class=\"text-medium\">Read more about Anna<\/span><i class=\"arrow fa fa-arrow-right\" aria-hidden=\"true\"><\/i>\n            <\/a>\n        <\/div>\n    <\/div>\n    \n<\/div>\n                                    \n<div class=\"row__col row__col--lg-3 listing-block--item cols-4\" >\n    <div class=\"listing-block--item-inner\">\n                <a class=\"m-0\" href=\"https:\/\/novare.se\/tech\/en\/employees\/anna-jansson\/\">\n            <div class=\"image m-0\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"670\" height=\"480\" src=\"https:\/\/novare.se\/wp-content\/uploads\/sites\/9\/2024\/04\/Anna_Jansson_Tiny.jpg\" class=\"media-item\" alt=\"\" srcset=\"https:\/\/novare.se\/wp-content\/uploads\/sites\/9\/2024\/04\/Anna_Jansson_Tiny.jpg 670w, https:\/\/novare.se\/wp-content\/uploads\/sites\/9\/2024\/04\/Anna_Jansson_Tiny-180x129.jpg 180w, https:\/\/novare.se\/wp-content\/uploads\/sites\/9\/2024\/04\/Anna_Jansson_Tiny-200x143.jpg 200w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/>                <div class=\"overlay\"><\/div>\n                <div class=\"badge text-regular\" style=\"background-color: #f5f2ef; color: #000000;\">Novare Tech<\/div>            <\/div>\n        <\/a>\n        <div class=\"content\">\n            <div class=\"header\">\n                <div class=\"name\">\n                    <a class=\"m-0\" href=\"https:\/\/novare.se\/tech\/en\/employees\/anna-jansson\/\">\n                        <div class=\"title text-medium\"><p>Anna Jansson<\/p><\/div>\n                    <\/a>\n                    <div class=\"pre_title\"><p>Researcher<\/p><\/div>\n                <\/div>\n                                    <div class=\"contact-info\">\n                        <a class=\"m-0\" href=\"mailto:anna.jansson@novare.se\"><span class=\"text-medium\">anna.jansson@novare.se<\/span><\/a>  \n                        <a class=\"m-0\" href=\"tel:+46 735 28 64 37\"><span class=\"text-medium\">+46 735 28 64 37<\/span><\/a>  \n                    <\/div>\n                  \n            <\/div>\n                \n            <a class=\"m-0 read-more\" href=\"https:\/\/novare.se\/tech\/en\/employees\/anna-jansson\/\">\n                <span class=\"text-medium\">Read more about Anna<\/span><i class=\"arrow fa fa-arrow-right\" aria-hidden=\"true\"><\/i>\n            <\/a>\n        <\/div>\n    <\/div>\n    \n<\/div>\n                                    \n<div class=\"row__col row__col--lg-3 listing-block--item cols-4\" >\n    <div class=\"listing-block--item-inner\">\n                <a class=\"m-0\" href=\"https:\/\/novare.se\/executive-search\/en\/employees\/anna-malmstrom\/\">\n            <div class=\"image m-0\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"670\" height=\"480\" src=\"https:\/\/novare.se\/wp-content\/uploads\/sites\/2\/2024\/05\/Anna_Malmstrom_Tiny.jpg\" class=\"media-item\" alt=\"\" srcset=\"https:\/\/novare.se\/wp-content\/uploads\/sites\/2\/2024\/05\/Anna_Malmstrom_Tiny.jpg 670w, https:\/\/novare.se\/wp-content\/uploads\/sites\/2\/2024\/05\/Anna_Malmstrom_Tiny-180x129.jpg 180w, https:\/\/novare.se\/wp-content\/uploads\/sites\/2\/2024\/05\/Anna_Malmstrom_Tiny-200x143.jpg 200w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/>                <div class=\"overlay\"><\/div>\n                <div class=\"badge text-regular\" style=\"background-color: #f5f2ef; color: #000000;\">Novare Executive Search<\/div>            <\/div>\n        <\/a>\n        <div class=\"content\">\n            <div class=\"header\">\n                <div class=\"name\">\n                    <a class=\"m-0\" href=\"https:\/\/novare.se\/executive-search\/en\/employees\/anna-malmstrom\/\">\n                        <div class=\"title text-medium\"><p>Anna Malmstr\u00f6m<\/p><\/div>\n                    <\/a>\n                    <div class=\"pre_title\"><p>Partner &#038; Senior Consultant<\/p><\/div>\n                <\/div>\n                                    <div class=\"contact-info\">\n                        <a class=\"m-0\" href=\"mailto:anna.malmstrom@novare.se\"><span class=\"text-medium\">anna.malmstrom@novare.se<\/span><\/a>  \n                        <a class=\"m-0\" href=\"tel:+ 46 735 23 30 14\"><span class=\"text-medium\">+ 46 735 23 30 14<\/span><\/a>  \n                    <\/div>\n                  \n            <\/div>\n                \n            <a class=\"m-0 read-more\" href=\"https:\/\/novare.se\/executive-search\/en\/employees\/anna-malmstrom\/\">\n                <span class=\"text-medium\">Read more about Anna<\/span><i class=\"arrow fa fa-arrow-right\" aria-hidden=\"true\"><\/i>\n            <\/a>\n        <\/div>\n    <\/div>\n    \n<\/div>\n                                    \n<div class=\"row__col row__col--lg-3 listing-block--item cols-4\" >\n    <div class=\"listing-block--item-inner\">\n                <a class=\"m-0\" href=\"https:\/\/novare.se\/executive-search\/en\/employees\/anna-schauman\/\">\n            <div class=\"image m-0\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"670\" height=\"480\" src=\"https:\/\/novare.se\/wp-content\/uploads\/sites\/2\/2024\/05\/Anna_Schauman_Tiny.jpg\" class=\"media-item\" alt=\"\" srcset=\"https:\/\/novare.se\/wp-content\/uploads\/sites\/2\/2024\/05\/Anna_Schauman_Tiny.jpg 670w, https:\/\/novare.se\/wp-content\/uploads\/sites\/2\/2024\/05\/Anna_Schauman_Tiny-180x129.jpg 180w, https:\/\/novare.se\/wp-content\/uploads\/sites\/2\/2024\/05\/Anna_Schauman_Tiny-200x143.jpg 200w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/>                <div class=\"overlay\"><\/div>\n                <div class=\"badge text-regular\" style=\"background-color: #f5f2ef; color: #000000;\">Novare Executive Search<\/div>            <\/div>\n        <\/a>\n        <div class=\"content\">\n            <div class=\"header\">\n                <div class=\"name\">\n                    <a class=\"m-0\" href=\"https:\/\/novare.se\/executive-search\/en\/employees\/anna-schauman\/\">\n                        <div class=\"title text-medium\"><p>Anna Schauman<\/p><\/div>\n                    <\/a>\n                    <div class=\"pre_title\"><p>Senior Partner &#038; Senior Consultant<\/p><\/div>\n                <\/div>\n                                    <div class=\"contact-info\">\n                        <a class=\"m-0\" href=\"mailto:anna.schauman@novare.se\"><span class=\"text-medium\">anna.schauman@novare.se<\/span><\/a>  \n                        <a class=\"m-0\" href=\"tel:+46 760 02 45 75\"><span class=\"text-medium\">+46 760 02 45 75<\/span><\/a>  \n                    <\/div>\n                  \n            <\/div>\n                \n            <a class=\"m-0 read-more\" href=\"https:\/\/novare.se\/executive-search\/en\/employees\/anna-schauman\/\">\n                <span class=\"text-medium\">Read more about Anna<\/span><i class=\"arrow fa fa-arrow-right\" aria-hidden=\"true\"><\/i>\n            <\/a>\n        <\/div>\n    <\/div>\n    \n<\/div>\n                                    \n<div class=\"row__col row__col--lg-3 listing-block--item cols-4\" >\n    <div class=\"listing-block--item-inner\">\n                <a class=\"m-0\" href=\"https:\/\/novare.se\/executive-search\/en\/employees\/anna-skalman\/\">\n            <div class=\"image m-0\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"670\" height=\"480\" src=\"https:\/\/novare.se\/wp-content\/uploads\/sites\/2\/2024\/05\/Anna_Skalman_Tiny.jpg\" class=\"media-item\" alt=\"\" srcset=\"https:\/\/novare.se\/wp-content\/uploads\/sites\/2\/2024\/05\/Anna_Skalman_Tiny.jpg 670w, https:\/\/novare.se\/wp-content\/uploads\/sites\/2\/2024\/05\/Anna_Skalman_Tiny-180x129.jpg 180w, https:\/\/novare.se\/wp-content\/uploads\/sites\/2\/2024\/05\/Anna_Skalman_Tiny-200x143.jpg 200w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/>                <div class=\"overlay\"><\/div>\n                <div class=\"badge text-regular\" style=\"background-color: #f5f2ef; color: #000000;\">Novare Executive Search<\/div>            <\/div>\n        <\/a>\n        <div class=\"content\">\n            <div class=\"header\">\n                <div class=\"name\">\n                    <a class=\"m-0\" href=\"https:\/\/novare.se\/executive-search\/en\/employees\/anna-skalman\/\">\n                        <div class=\"title text-medium\"><p>Anna Skalman<\/p><\/div>\n                    <\/a>\n                    <div class=\"pre_title\"><p>Head of Business Support<\/p><\/div>\n                <\/div>\n                                    <div class=\"contact-info\">\n                        <a class=\"m-0\" href=\"mailto:anna.skalman@novare.se\"><span class=\"text-medium\">anna.skalman@novare.se<\/span><\/a>  \n                        <a class=\"m-0\" href=\"tel:+46 725 65 36 26\"><span class=\"text-medium\">+46 725 65 36 26<\/span><\/a>  \n                    <\/div>\n                  \n            <\/div>\n                \n            <a class=\"m-0 read-more\" href=\"https:\/\/novare.se\/executive-search\/en\/employees\/anna-skalman\/\">\n                <span class=\"text-medium\">Read more about Anna<\/span><i class=\"arrow fa fa-arrow-right\" aria-hidden=\"true\"><\/i>\n            <\/a>\n        <\/div>\n    <\/div>\n    \n<\/div>\n                                    \n<div class=\"row__col row__col--lg-3 listing-block--item cols-4\" >\n    <div class=\"listing-block--item-inner\">\n                <a class=\"m-0\" href=\"https:\/\/novare.se\/interim-and-recruitment\/en\/employees\/anna-sward\/\">\n            <div class=\"image m-0\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/novare.se\/wp-content\/uploads\/sites\/5\/2026\/03\/Anna_Sward_webb-768x768.png\" class=\"media-item\" alt=\"\" srcset=\"https:\/\/novare.se\/wp-content\/uploads\/sites\/5\/2026\/03\/Anna_Sward_webb-768x768.png 768w, https:\/\/novare.se\/wp-content\/uploads\/sites\/5\/2026\/03\/Anna_Sward_webb-360x360.png 360w, https:\/\/novare.se\/wp-content\/uploads\/sites\/5\/2026\/03\/Anna_Sward_webb-1024x1024.png 1024w, https:\/\/novare.se\/wp-content\/uploads\/sites\/5\/2026\/03\/Anna_Sward_webb-150x150.png 150w, https:\/\/novare.se\/wp-content\/uploads\/sites\/5\/2026\/03\/Anna_Sward_webb-1536x1536.png 1536w, https:\/\/novare.se\/wp-content\/uploads\/sites\/5\/2026\/03\/Anna_Sward_webb.png 2000w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>                <div class=\"overlay\"><\/div>\n                <div class=\"badge text-regular\" style=\"background-color: #f5f2ef; color: #000000;\">Novare Interim &#038; Recruitment<\/div>            <\/div>\n        <\/a>\n        <div class=\"content\">\n            <div class=\"header\">\n                <div class=\"name\">\n                    <a class=\"m-0\" href=\"https:\/\/novare.se\/interim-and-recruitment\/en\/employees\/anna-sward\/\">\n                        <div class=\"title text-medium\"><p>Anna Sw\u00e4rd<\/p><\/div>\n                    <\/a>\n                    <div class=\"pre_title\"><p>Client Executive<\/p><\/div>\n                <\/div>\n                                    <div class=\"contact-info\">\n                        <a class=\"m-0\" href=\"mailto:anna.sward@novare.se\"><span class=\"text-medium\">anna.sward@novare.se<\/span><\/a>  \n                        <a class=\"m-0\" href=\"tel:+46 70 353 30 58\"><span class=\"text-medium\">+46 70 353 30 58<\/span><\/a>  \n                    <\/div>\n                  \n            <\/div>\n                \n            <a class=\"m-0 read-more\" href=\"https:\/\/novare.se\/interim-and-recruitment\/en\/employees\/anna-sward\/\">\n                <span class=\"text-medium\">Read more about Anna<\/span><i class=\"arrow fa fa-arrow-right\" aria-hidden=\"true\"><\/i>\n            <\/a>\n        <\/div>\n    <\/div>\n    \n<\/div>\n                                    \n<div class=\"row__col row__col--lg-3 listing-block--item cols-4\" >\n    <div class=\"listing-block--item-inner\">\n                <a class=\"m-0\" href=\"https:\/\/novare.se\/executive-search\/en\/employees\/anna-werner\/\">\n            <div class=\"image m-0\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"670\" height=\"480\" src=\"https:\/\/novare.se\/wp-content\/uploads\/sites\/2\/2026\/06\/Anna_Werner_webb.jpg\" class=\"media-item\" alt=\"\" srcset=\"https:\/\/novare.se\/wp-content\/uploads\/sites\/2\/2026\/06\/Anna_Werner_webb.jpg 670w, https:\/\/novare.se\/wp-content\/uploads\/sites\/2\/2026\/06\/Anna_Werner_webb-360x258.jpg 360w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/>                <div class=\"overlay\"><\/div>\n                <div class=\"badge text-regular\" style=\"background-color: #f5f2ef; color: #000000;\">Novare Executive Search<\/div>            <\/div>\n        <\/a>\n        <div class=\"content\">\n            <div class=\"header\">\n                <div class=\"name\">\n                    <a class=\"m-0\" href=\"https:\/\/novare.se\/executive-search\/en\/employees\/anna-werner\/\">\n                        <div class=\"title text-medium\"><p>Anna Werner<\/p><\/div>\n                    <\/a>\n                    <div class=\"pre_title\"><p>Consultant<\/p><\/div>\n                <\/div>\n                                    <div class=\"contact-info\">\n                        <a class=\"m-0\" href=\"mailto:anna.werner@novare.se\"><span class=\"text-medium\">anna.werner@novare.se<\/span><\/a>  \n                        <a class=\"m-0\" href=\"tel:+46 73-500 22 99\"><span class=\"text-medium\">+46 73500 22 99<\/span><\/a>  \n                    <\/div>\n                  \n            <\/div>\n                \n            <a class=\"m-0 read-more\" href=\"https:\/\/novare.se\/executive-search\/en\/employees\/anna-werner\/\">\n                <span class=\"text-medium\">Read more about Anna<\/span><i class=\"arrow fa fa-arrow-right\" aria-hidden=\"true\"><\/i>\n            <\/a>\n        <\/div>\n    <\/div>\n    \n<\/div>\n                                    \n<div class=\"row__col row__col--lg-3 listing-block--item cols-4\" >\n    <div class=\"listing-block--item-inner\">\n                <a class=\"m-0\" href=\"https:\/\/novare.se\/executive-search\/en\/employees\/annica-granlund\/\">\n            <div class=\"image m-0\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"670\" height=\"480\" src=\"https:\/\/novare.se\/wp-content\/uploads\/sites\/2\/2024\/05\/Annica_Granlund_Tiny.jpg\" class=\"media-item\" alt=\"\" srcset=\"https:\/\/novare.se\/wp-content\/uploads\/sites\/2\/2024\/05\/Annica_Granlund_Tiny.jpg 670w, https:\/\/novare.se\/wp-content\/uploads\/sites\/2\/2024\/05\/Annica_Granlund_Tiny-180x129.jpg 180w, https:\/\/novare.se\/wp-content\/uploads\/sites\/2\/2024\/05\/Annica_Granlund_Tiny-200x143.jpg 200w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/>                <div class=\"overlay\"><\/div>\n                <div class=\"badge text-regular\" style=\"background-color: #f5f2ef; color: #000000;\">Novare Executive Search<\/div>            <\/div>\n        <\/a>\n        <div class=\"content\">\n            <div class=\"header\">\n                <div class=\"name\">\n                    <a class=\"m-0\" href=\"https:\/\/novare.se\/executive-search\/en\/employees\/annica-granlund\/\">\n                        <div class=\"title text-medium\"><p>Annica Granlund<\/p><\/div>\n                    <\/a>\n                    <div class=\"pre_title\"><p>Team Coordinator<\/p><\/div>\n                <\/div>\n                                    <div class=\"contact-info\">\n                        <a class=\"m-0\" href=\"mailto:annica.granlund@novare.se\"><span class=\"text-medium\">annica.granlund@novare.se<\/span><\/a>  \n                        <a class=\"m-0\" href=\"tel:+46 703 22 75 55\"><span class=\"text-medium\">+46 703 22 75 55<\/span><\/a>  \n                    <\/div>\n                  \n            <\/div>\n                \n            <a class=\"m-0 read-more\" href=\"https:\/\/novare.se\/executive-search\/en\/employees\/annica-granlund\/\">\n                <span class=\"text-medium\">Read more about Annica<\/span><i class=\"arrow fa fa-arrow-right\" aria-hidden=\"true\"><\/i>\n            <\/a>\n        <\/div>\n    <\/div>\n    \n<\/div>\n                                    \n<div class=\"row__col row__col--lg-3 listing-block--item cols-4\" >\n    <div class=\"listing-block--item-inner\">\n                <a class=\"m-0\" href=\"https:\/\/novare.se\/interim-and-recruitment\/en\/employees\/annika-domeij\/\">\n            <div class=\"image m-0\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"670\" height=\"480\" src=\"https:\/\/novare.se\/wp-content\/uploads\/sites\/5\/2024\/04\/Annika_Domeij_Tiny.jpg\" class=\"media-item\" alt=\"\" srcset=\"https:\/\/novare.se\/wp-content\/uploads\/sites\/5\/2024\/04\/Annika_Domeij_Tiny.jpg 670w, https:\/\/novare.se\/wp-content\/uploads\/sites\/5\/2024\/04\/Annika_Domeij_Tiny-180x129.jpg 180w, https:\/\/novare.se\/wp-content\/uploads\/sites\/5\/2024\/04\/Annika_Domeij_Tiny-200x143.jpg 200w, https:\/\/novare.se\/wp-content\/uploads\/sites\/5\/2024\/04\/Annika_Domeij_Tiny-500x358.jpg 500w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/>                <div class=\"overlay\"><\/div>\n                <div class=\"badge text-regular\" style=\"background-color: #f5f2ef; color: #000000;\">Novare Interim &#038; Recruitment<\/div>            <\/div>\n        <\/a>\n        <div class=\"content\">\n            <div class=\"header\">\n                <div class=\"name\">\n                    <a class=\"m-0\" href=\"https:\/\/novare.se\/interim-and-recruitment\/en\/employees\/annika-domeij\/\">\n                        <div class=\"title text-medium\"><p>Annika Domeij<\/p><\/div>\n                    <\/a>\n                    <div class=\"pre_title\"><p>Head of People<\/p><\/div>\n                <\/div>\n                                    <div class=\"contact-info\">\n                        <a class=\"m-0\" href=\"mailto:annika.domeij@novare.se\"><span class=\"text-medium\">annika.domeij@novare.se<\/span><\/a>  \n                        <a class=\"m-0\" href=\"tel:+46 723 00 05 21\"><span class=\"text-medium\">+46 723 00 05 21<\/span><\/a>  \n                    <\/div>\n                  \n            <\/div>\n                \n            <a class=\"m-0 read-more\" href=\"https:\/\/novare.se\/interim-and-recruitment\/en\/employees\/annika-domeij\/\">\n                <span class=\"text-medium\">Read more about Annika<\/span><i class=\"arrow fa fa-arrow-right\" aria-hidden=\"true\"><\/i>\n            <\/a>\n        <\/div>\n    <\/div>\n    \n<\/div>\n                                    \n<div class=\"row__col row__col--lg-3 listing-block--item cols-4\" >\n    <div class=\"listing-block--item-inner\">\n                <a class=\"m-0\" href=\"https:\/\/novare.se\/executive-search\/en\/employees\/annika-wahlstedt\/\">\n            <div class=\"image m-0\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"670\" height=\"480\" src=\"https:\/\/novare.se\/wp-content\/uploads\/sites\/2\/2024\/05\/Annika_Wahlstedt_Tiny.jpg\" class=\"media-item\" alt=\"\" srcset=\"https:\/\/novare.se\/wp-content\/uploads\/sites\/2\/2024\/05\/Annika_Wahlstedt_Tiny.jpg 670w, https:\/\/novare.se\/wp-content\/uploads\/sites\/2\/2024\/05\/Annika_Wahlstedt_Tiny-180x129.jpg 180w, https:\/\/novare.se\/wp-content\/uploads\/sites\/2\/2024\/05\/Annika_Wahlstedt_Tiny-200x143.jpg 200w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/>                <div class=\"overlay\"><\/div>\n                <div class=\"badge text-regular\" style=\"background-color: #f5f2ef; color: #000000;\">Novare Executive Search<\/div>            <\/div>\n        <\/a>\n        <div class=\"content\">\n            <div class=\"header\">\n                <div class=\"name\">\n                    <a class=\"m-0\" href=\"https:\/\/novare.se\/executive-search\/en\/employees\/annika-wahlstedt\/\">\n                        <div class=\"title text-medium\"><p>Annika Wahlstedt<\/p><\/div>\n                    <\/a>\n                    <div class=\"pre_title\"><p>Senior Consultant<\/p><\/div>\n                <\/div>\n                                    <div class=\"contact-info\">\n                        <a class=\"m-0\" href=\"mailto:annika.wahlstedt@novare.se\"><span class=\"text-medium\">annika.wahlstedt@novare.se<\/span><\/a>  \n                        <a class=\"m-0\" href=\"tel:+46 707 41 00 53\"><span class=\"text-medium\">+46 707 41 00 53<\/span><\/a>  \n                    <\/div>\n                  \n            <\/div>\n                \n            <a class=\"m-0 read-more\" href=\"https:\/\/novare.se\/executive-search\/en\/employees\/annika-wahlstedt\/\">\n                <span class=\"text-medium\">Read more about Annika<\/span><i class=\"arrow fa fa-arrow-right\" aria-hidden=\"true\"><\/i>\n            <\/a>\n        <\/div>\n    <\/div>\n    \n<\/div>\n                                    \n<div class=\"row__col row__col--lg-3 listing-block--item cols-4\" >\n    <div class=\"listing-block--item-inner\">\n                <a class=\"m-0\" href=\"https:\/\/novare.se\/executive-search\/en\/employees\/antonia-hagg\/\">\n            <div class=\"image m-0\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"670\" height=\"480\" src=\"https:\/\/novare.se\/wp-content\/uploads\/sites\/2\/2024\/05\/Antonia_Hagg_Tiny.jpg\" class=\"media-item\" alt=\"\" srcset=\"https:\/\/novare.se\/wp-content\/uploads\/sites\/2\/2024\/05\/Antonia_Hagg_Tiny.jpg 670w, https:\/\/novare.se\/wp-content\/uploads\/sites\/2\/2024\/05\/Antonia_Hagg_Tiny-180x129.jpg 180w, https:\/\/novare.se\/wp-content\/uploads\/sites\/2\/2024\/05\/Antonia_Hagg_Tiny-200x143.jpg 200w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/>                <div class=\"overlay\"><\/div>\n                <div class=\"badge text-regular\" style=\"background-color: #f5f2ef; color: #000000;\">Novare Executive Search<\/div>            <\/div>\n        <\/a>\n        <div class=\"content\">\n            <div class=\"header\">\n                <div class=\"name\">\n                    <a class=\"m-0\" href=\"https:\/\/novare.se\/executive-search\/en\/employees\/antonia-hagg\/\">\n                        <div class=\"title text-medium\"><p>Antonia H\u00e4gg<\/p><\/div>\n                    <\/a>\n                    <div class=\"pre_title\"><p>Partner &#038; Senior Consultant<\/p><\/div>\n                <\/div>\n                                    <div class=\"contact-info\">\n                        <a class=\"m-0\" href=\"mailto:antonia.hagg@novare.se\"><span class=\"text-medium\">antonia.hagg@novare.se<\/span><\/a>  \n                        <a class=\"m-0\" href=\"tel:+46 708 58 70 56\"><span class=\"text-medium\">+46 708 58 70 56<\/span><\/a>  \n                    <\/div>\n                  \n            <\/div>\n                \n            <a class=\"m-0 read-more\" href=\"https:\/\/novare.se\/executive-search\/en\/employees\/antonia-hagg\/\">\n                <span class=\"text-medium\">Read more about Antonia<\/span><i class=\"arrow fa fa-arrow-right\" aria-hidden=\"true\"><\/i>\n            <\/a>\n        <\/div>\n    <\/div>\n    \n<\/div>\n                                    \n<div class=\"row__col row__col--lg-3 listing-block--item cols-4\" >\n    <div class=\"listing-block--item-inner\">\n                <a class=\"m-0\" href=\"https:\/\/novare.se\/en\/employees\/arja-jauhiainen\/\">\n            <div class=\"image m-0\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/novare.se\/wp-content\/uploads\/2026\/05\/arja_jauhiainen_webb-768x768.jpg\" class=\"media-item\" alt=\"\" srcset=\"https:\/\/novare.se\/wp-content\/uploads\/2026\/05\/arja_jauhiainen_webb-768x768.jpg 768w, https:\/\/novare.se\/wp-content\/uploads\/2026\/05\/arja_jauhiainen_webb-360x360.jpg 360w, https:\/\/novare.se\/wp-content\/uploads\/2026\/05\/arja_jauhiainen_webb-150x150.jpg 150w, https:\/\/novare.se\/wp-content\/uploads\/2026\/05\/arja_jauhiainen_webb.jpg 1024w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>                <div class=\"overlay\"><\/div>\n                <div class=\"badge text-regular\" style=\"background-color: #f5f2ef; color: #000000;\">Novare<\/div>            <\/div>\n        <\/a>\n        <div class=\"content\">\n            <div class=\"header\">\n                <div class=\"name\">\n                    <a class=\"m-0\" href=\"https:\/\/novare.se\/en\/employees\/arja-jauhiainen\/\">\n                        <div class=\"title text-medium\"><p>Arja Jauhiainen<\/p><\/div>\n                    <\/a>\n                    <div class=\"pre_title\"><p>Accounting Assistant<\/p><\/div>\n                <\/div>\n                                    <div class=\"contact-info\">\n                        <a class=\"m-0\" href=\"mailto:arja.jauhiainen@novare.se\"><span class=\"text-medium\">arja.jauhiainen@novare.se<\/span><\/a>  \n                        <a class=\"m-0\" href=\"tel:+46 704 23 34 31\"><span class=\"text-medium\">+46 704 23 34 31<\/span><\/a>  \n                    <\/div>\n                  \n            <\/div>\n                \n            <a class=\"m-0 read-more\" href=\"https:\/\/novare.se\/en\/employees\/arja-jauhiainen\/\">\n                <span class=\"text-medium\">Read more about Arja<\/span><i class=\"arrow fa fa-arrow-right\" aria-hidden=\"true\"><\/i>\n            <\/a>\n        <\/div>\n    <\/div>\n    \n<\/div>\n                                    \n<div class=\"row__col row__col--lg-3 listing-block--item cols-4\" >\n    <div class=\"listing-block--item-inner\">\n                <a class=\"m-0\" href=\"https:\/\/novare.se\/intro\/en\/employees\/armin-haddad\/\">\n            <div class=\"image m-0\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"670\" height=\"480\" src=\"https:\/\/novare.se\/wp-content\/uploads\/sites\/3\/2023\/11\/Armin_Haddad_Tiny-1.jpg\" class=\"media-item\" alt=\"\" srcset=\"https:\/\/novare.se\/wp-content\/uploads\/sites\/3\/2023\/11\/Armin_Haddad_Tiny-1.jpg 670w, https:\/\/novare.se\/wp-content\/uploads\/sites\/3\/2023\/11\/Armin_Haddad_Tiny-1-360x258.jpg 360w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/>                <div class=\"overlay\"><\/div>\n                <div class=\"badge text-regular\" style=\"background-color: #f5f2ef; color: #000000;\">Novare Intro<\/div>            <\/div>\n        <\/a>\n        <div class=\"content\">\n            <div class=\"header\">\n                <div class=\"name\">\n                    <a class=\"m-0\" href=\"https:\/\/novare.se\/intro\/en\/employees\/armin-haddad\/\">\n                        <div class=\"title text-medium\"><p>Armin Haddad<\/p><\/div>\n                    <\/a>\n                    <div class=\"pre_title\"><p>Consultant Manager<\/p><\/div>\n                <\/div>\n                                    <div class=\"contact-info\">\n                        <a class=\"m-0\" href=\"mailto:armin.haddad@novare.se\"><span class=\"text-medium\">armin.haddad@novare.se<\/span><\/a>  \n                        <a class=\"m-0\" href=\"tel:+46 700 08 77 18\"><span class=\"text-medium\">+46 700 08 77 18<\/span><\/a>  \n                    <\/div>\n                  \n            <\/div>\n                \n            <a class=\"m-0 read-more\" href=\"https:\/\/novare.se\/intro\/en\/employees\/armin-haddad\/\">\n                <span class=\"text-medium\">Read more about Armin<\/span><i class=\"arrow fa fa-arrow-right\" aria-hidden=\"true\"><\/i>\n            <\/a>\n        <\/div>\n    <\/div>\n    \n<\/div>\n                                    \n<div class=\"row__col row__col--lg-3 listing-block--item cols-4\" >\n    <div class=\"listing-block--item-inner\">\n                <a class=\"m-0\" href=\"https:\/\/novare.se\/en\/employees\/axel-cedermark\/\">\n            <div class=\"image m-0\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/novare.se\/wp-content\/uploads\/2026\/08\/Medarbetarbild-Axel-768x768.png\" class=\"media-item\" alt=\"\" srcset=\"https:\/\/novare.se\/wp-content\/uploads\/2026\/08\/Medarbetarbild-Axel-768x768.png 768w, https:\/\/novare.se\/wp-content\/uploads\/2026\/08\/Medarbetarbild-Axel-360x360.png 360w, https:\/\/novare.se\/wp-content\/uploads\/2026\/08\/Medarbetarbild-Axel-1024x1024.png 1024w, https:\/\/novare.se\/wp-content\/uploads\/2026\/08\/Medarbetarbild-Axel-150x150.png 150w, https:\/\/novare.se\/wp-content\/uploads\/2026\/08\/Medarbetarbild-Axel-1536x1536.png 1536w, https:\/\/novare.se\/wp-content\/uploads\/2026\/08\/Medarbetarbild-Axel.png 2000w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>                <div class=\"overlay\"><\/div>\n                <div class=\"badge text-regular\" style=\"background-color: #f5f2ef; color: #000000;\">Novare<\/div>            <\/div>\n        <\/a>\n        <div class=\"content\">\n            <div class=\"header\">\n                <div class=\"name\">\n                    <a class=\"m-0\" href=\"https:\/\/novare.se\/en\/employees\/axel-cedermark\/\">\n                        <div class=\"title text-medium\"><p>Axel Cedermark<\/p><\/div>\n                    <\/a>\n                    <div class=\"pre_title\"><p>CEO, Novare Pay<\/p><\/div>\n                <\/div>\n                                    <div class=\"contact-info\">\n                        <a class=\"m-0\" href=\"mailto:axel.cedermark@novare.se\"><span class=\"text-medium\">axel.cedermark@novare.se<\/span><\/a>  \n                        <a class=\"m-0\" href=\"tel:070-632 32 02\"><span class=\"text-medium\">070632 32 02<\/span><\/a>  \n                    <\/div>\n                  \n            <\/div>\n                \n            <a class=\"m-0 read-more\" href=\"https:\/\/novare.se\/en\/employees\/axel-cedermark\/\">\n                <span class=\"text-medium\">Read more about Axel<\/span><i class=\"arrow fa fa-arrow-right\" aria-hidden=\"true\"><\/i>\n            <\/a>\n        <\/div>\n    <\/div>\n    \n<\/div>\n                                    <\/div>\n\n        <div class=\"row listing-block--pagination\">\n            <div class=\"row__col listing-block--pagination--results\">\n                                    <div class=\"pagination m-0\" data-max-num-pages=\"6\" data-current-page=\"1\"><button type=\"button\" data-page-no=\"1\" disabled class=\"m-0 btn--pagination pagination-item prev\"><i class=\"fa fa-chevron-left\"><\/i><\/button><button type=\"button\" data-page-no=\"1\" class=\"m-0 btn--pagination text-medium current bg-primary pagination-item\">1<\/button><button type=\"button\" data-page-no=\"2\" class=\"m-0 btn--pagination text-medium pagination-item\">2<\/button><button type=\"button\" data-page-no=\"3\" class=\"m-0 btn--pagination text-medium pagination-item\">3<\/button><span class=\"text-medium pagination-ellipsis\">&#8230;<\/span><button type=\"button\" data-page-no=\"6\" class=\"m-0 btn--pagination text-medium pagination-item\">6<\/button><button type=\"button\" data-page-no=\"2\"  class=\"m-0 btn--pagination text-medium pagination-item next\"><i class=\"fa fa-chevron-right\"><\/i><\/button><\/div>                            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"both","_seopress_redirections_param":"","_seopress_redirections_type":301,"_seopress_analysis_target_kw":"","_seopress_news_disabled":"","_seopress_video_disabled":"","_seopress_video":[],"_seopress_pro_schemas_manual":[],"_seopress_pro_rich_snippets_disable_all":"","_seopress_pro_rich_snippets_disable":[],"_seopress_pro_schemas":[],"inline_featured_image":false,"footnotes":""},"class_list":["post-48270","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/novare.se\/en\/wp-json\/wp\/v2\/pages\/48270","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novare.se\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/novare.se\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/novare.se\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/novare.se\/en\/wp-json\/wp\/v2\/comments?post=48270"}],"version-history":[{"count":1,"href":"https:\/\/novare.se\/en\/wp-json\/wp\/v2\/pages\/48270\/revisions"}],"predecessor-version":[{"id":48273,"href":"https:\/\/novare.se\/en\/wp-json\/wp\/v2\/pages\/48270\/revisions\/48273"}],"wp:attachment":[{"href":"https:\/\/novare.se\/en\/wp-json\/wp\/v2\/media?parent=48270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}